{"id":538,"date":"2025-08-07T16:07:38","date_gmt":"2025-08-07T15:07:38","guid":{"rendered":"https:\/\/novo.esocvp.org\/?page_id=538"},"modified":"2026-02-24T15:10:53","modified_gmt":"2026-02-24T15:10:53","slug":"sbv-dae-suporte-basico-de-vida-com-desfibrilhacao-automatica-externa","status":"publish","type":"page","link":"https:\/\/novo.esocvp.org\/index.php\/sbv-dae-suporte-basico-de-vida-com-desfibrilhacao-automatica-externa\/","title":{"rendered":"SBV\/DAE &#8211; Suporte B\u00e1sico de Vida com Desfibrilha\u00e7\u00e3o Autom\u00e1tica Externa"},"content":{"rendered":"\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-f56f613f wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<p class=\"has-background-color has-text-color has-link-color has-extra-small-font-size wp-elements-1 wp-block-paragraph\"><strong>Dura\u00e7\u00e3o:<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center has-extra-small-font-size wp-block-paragraph\">7 horas<\/p>\n\n\n\n<p class=\"has-background-color has-text-color has-link-color has-extra-small-font-size wp-elements-2 wp-block-paragraph\"><strong>Objetivo:<\/strong><\/p>\n\n\n\n<p class=\"has-extra-small-font-size wp-block-paragraph\">Adquirir compet\u00eancias que lhe permitam realizar corretamente manobras de SBV com utiliza\u00e7\u00e3o de um Desfibrilhador Autom\u00e1tico Externo (DAE), numa v\u00edtima em paragem cardiorrespirat\u00f3ria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-background-color has-text-color has-link-color has-extra-small-font-size wp-elements-3 wp-block-paragraph\"><strong>Destinat\u00e1rios:<\/strong><\/p>\n\n\n\n<p class=\"has-extra-small-font-size wp-block-paragraph\">Este curso destina-se a profissionais de sa\u00fade e leigos, com dom\u00ednio da l\u00edngua portuguesa e com idade m\u00ednima de 16 anos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-background-color has-text-color has-link-color has-extra-small-font-size wp-elements-4 wp-block-paragraph\"><strong>Conte\u00fados Program\u00e1ticos:<\/strong><\/p>\n\n\n\n<p class=\"has-extra-small-font-size wp-block-paragraph\">Cadeia de Sobreviv\u00eancia; riscos para o reanimador; Algoritmo de SBV; posi\u00e7\u00e3o lateral de seguran\u00e7a; Algoritmos de desobstru\u00e7\u00e3o da via a\u00e9rea; algoritmos de SBV com DAE.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-background-color has-text-color has-link-color has-extra-small-font-size wp-elements-5 wp-block-paragraph\"><strong>Inclui:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"has-extra-small-font-size\">Certificado digital emitido aos formandos aprovados, v\u00e1lido por 5 anos;<\/li>\n\n\n\n<li class=\"has-extra-small-font-size\">Manuais e v\u00eddeos dispon\u00edveis para download atrav\u00e9s de inscri\u00e7\u00e3o na plataforma APRENDER &#8211; <a href=\"https:\/\/aprender.inem.pt\/login\/index.php\">https:\/\/aprender.inem.pt\/login\/index.php<\/a><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-background-color has-text-color has-link-color has-extra-small-font-size wp-elements-6 wp-block-paragraph\"><strong>Informa\u00e7\u00f5es:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list has-extra-small-font-size\">\n<li>N\u00e3o s\u00e3o permitidas faltas;<\/li>\n\n\n\n<li>Utiliza\u00e7\u00e3o de vestu\u00e1rio confort\u00e1vel e cal\u00e7ado pr\u00e1tico;<\/li>\n\n\n\n<li>Apresenta\u00e7\u00e3o do documento de identifica\u00e7\u00e3o no primeiro dia;<\/li>\n\n\n\n<li>Este curso n\u00e3o confere a credencia\u00e7\u00e3o de socorrista, apenas assegura que o formando est\u00e1 apto para atuar em caso de paragem cardiorrespirat\u00f3ria.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-f56f613f wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h5 class=\"wp-block-heading has-background-color has-text-color has-link-color has-extra-small-font-size wp-elements-7\"><strong>Pre\u00e7\u00e1rio:<\/strong><\/h5>\n\n\n\n<p class=\"has-heading-color has-text-color has-link-color has-extra-small-font-size wp-elements-8 wp-block-paragraph\"><strong>Inscri\u00e7\u00e3o individual:<\/strong> 65,00 \u20ac &#8211; contacte <a href=\"mailto:eso.geral@esocvp.org\">eso.geral@esocvp.org<\/a><\/p>\n\n\n\n<p class=\"has-heading-color has-text-color has-link-color has-extra-small-font-size wp-elements-9 wp-block-paragraph\"><strong>Entidades:<\/strong> Sob consulta \u2013 contacte&nbsp;<a href=\"mailto:eso.planeamento1@esocvp.org\">eso.planeamento1@esocvp.org<\/a><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-20959078 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-width wp-block-button__width-100\"><a class=\"wp-block-button__link has-text-align-center wp-element-button\" href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSewk_MjpbB18bYKqOxF4cLaiVnY0zKXlqGxsRCtvAstDVXr8g\/viewform\" style=\"padding-top:var(--wp--preset--spacing--40);padding-right:0;padding-bottom:var(--wp--preset--spacing--40);padding-left:0\"><strong>Formul\u00e1rio Pr\u00e9-Inscri\u00e7\u00e3o<\/strong><\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-text-align-center has-white-color has-cyan-bluish-gray-background-color has-text-color has-background has-link-color wp-elements-10 wp-block-paragraph\" style=\"padding-top:var(--wp--preset--spacing--20);padding-right:0;padding-bottom:var(--wp--preset--spacing--20);padding-left:0\"><strong>Forma\u00e7\u00e3o SBV\/DAE agendada, nos dias abaixo assinalados<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n\r\n<div id='mc-948a6a8e8cd15db324902317a630b853' class='mc-main mcjs listjs gridjs minijs ajaxjs light calendar month mc-948a6a8e8cd15db324902317a630b853 has-modal is-main-view' >\n<script type=\"application\/ld+json\">\n[{\"@context\":\"https:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"SBV\/DAE\",\"description\":\"SBV\/DAE - Suporte B\\u00e1sico de Vida com Desfibrilha\\u00e7\\u00e3o Autom\\u00e1tica Externa Adquirir compet\\u00eancias que lhe permitam realizar corretamente manobras de SBV com utiliza\\u00e7\\u00e3o de um Desfibrilhador Autom\\u00e1tico Externo (DAE), numa v\\u00edtima em paragem cardiorrespirat\\u00f3ria. SABER MAIS DETALHES SOBRE ESTA FORMA\\u00c7\\u00c3O &nbsp; Formul\\u00e1rio Pr\\u00e9-Inscri\\u00e7\\u00e3o Avenida de Ceuta, n\\u00ba 1 - 13\\u00ba Piso || 1300-125 LISBOA\",\"image\":\"https:\/\/novo.esocvp.org\/wp-content\/uploads\/2025\/07\/cropped-FaviconESO.webp\",\"url\":\"https:\/\/novo.esocvp.org\/index.php\/mc-events\/sbv-dae-22\/\",\"startDate\":\"2026-09-14T09:00:00+01:00\",\"endDate\":\"2026-09-14T17:00:00+01:00\",\"duration\":\"PT8H\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"location\":{\"@context\":\"https:\/\/schema.org\",\"@type\":\"Place\",\"name\":\"Morada ESO\",\"description\":\"\",\"url\":\"https:\/\/novo.esocvp.org\/index.php\/mc-locations\/morada-eso\/\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Avenida de Ceuta, n\\u00ba1\",\"addressLocality\":\"Lisboa\",\"addressRegion\":\"Lisboa\",\"postalCode\":\"1300 - 125\",\"addressCountry\":\"Lisboa\"},\"telephone\":\"21 845 94 40\",\"sameAs\":\"\",\"geo\":{\"@type\":\"GeoCoordinates\",\"latitude\":\"38.712933\",\"longitude\":\"-9.175846\"}}},{\"@context\":\"https:\/\/schema.org\",\"@type\":\"Event\",\"name\":\"SBV\/DAE\",\"description\":\"SBV\/DAE - Suporte B\\u00e1sico de Vida com Desfibrilha\\u00e7\\u00e3o Autom\\u00e1tica Externa Adquirir compet\\u00eancias que lhe permitam realizar corretamente manobras de SBV com utiliza\\u00e7\\u00e3o de um Desfibrilhador Autom\\u00e1tico Externo (DAE), numa v\\u00edtima em paragem cardiorrespirat\\u00f3ria. SABER MAIS DETALHES SOBRE ESTA FORMA\\u00c7\\u00c3O &nbsp; Formul\\u00e1rio Pr\\u00e9-Inscri\\u00e7\\u00e3o Avenida de Ceuta, n\\u00ba 1 - 13\\u00ba Piso || 1300-125 LISBOA\",\"image\":\"https:\/\/novo.esocvp.org\/wp-content\/uploads\/2025\/07\/cropped-FaviconESO.webp\",\"url\":\"https:\/\/novo.esocvp.org\/index.php\/mc-events\/sbv-dae-23\/\",\"startDate\":\"2026-09-26T09:00:00+01:00\",\"endDate\":\"2026-09-26T17:00:00+01:00\",\"duration\":\"PT8H\",\"eventAttendanceMode\":\"https:\/\/schema.org\/OfflineEventAttendanceMode\",\"location\":{\"@context\":\"https:\/\/schema.org\",\"@type\":\"Place\",\"name\":\"Morada ESO\",\"description\":\"\",\"url\":\"https:\/\/novo.esocvp.org\/index.php\/mc-locations\/morada-eso\/\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"Avenida de Ceuta, n\\u00ba1\",\"addressLocality\":\"Lisboa\",\"addressRegion\":\"Lisboa\",\"postalCode\":\"1300 - 125\",\"addressCountry\":\"Lisboa\"},\"telephone\":\"21 845 94 40\",\"sameAs\":\"\",\"geo\":{\"@type\":\"GeoCoordinates\",\"latitude\":\"38.712933\",\"longitude\":\"-9.175846\"}}}]\n<\/script>\n<h2 id=\"mc_head_mc-948a6a8e8cd15db324902317a630b853\" class=\"heading my-calendar-month\"><span>Eventos em Setembro 2026<\/span><\/h2>\n\n<nav class=\"my-calendar-navigation\" aria-label=\"Calendar (top)\">\n<div class=\"my-calendar-header\"><div class='mc-format'>\r\n\t\t<ul><li><button type='button' id='mc_grid-mc-948a6a8e8cd15db324902317a630b853' data-href='https:\/\/novo.esocvp.org\/index.php\/sbv-dae-suporte-basico-de-vida-com-desfibrilhacao-automatica-externa\/?format=calendar' aria-pressed=\"true\" class='mc-navigation-button mc-grid-option mc-active'><span class='mc-icon' aria-hidden='true'><\/span><span class=\"maybe-hide\">Ver como<\/span>Grid<\/button><\/li><li><button type='button' id='mc_list-mc-948a6a8e8cd15db324902317a630b853' data-href='https:\/\/novo.esocvp.org\/index.php\/sbv-dae-suporte-basico-de-vida-com-desfibrilhacao-automatica-externa\/?format=list'  class='mc-navigation-button mc-list-option'><span class='mc-icon' aria-hidden='true'><\/span><span class=\"maybe-hide\">Ver como <\/span>Lista<\/button><\/li><\/ul>\r\n\t\t<\/div><div class='mc-time'><ul><li><button type='button' id='mc_month-mc-948a6a8e8cd15db324902317a630b853' data-href='https:\/\/novo.esocvp.org\/index.php\/sbv-dae-suporte-basico-de-vida-com-desfibrilhacao-automatica-externa\/?cid=mc-948a6a8e8cd15db324902317a630b853&#038;time=month' class='mc-navigation-button month mc-active' aria-pressed='true'>M\u00eas<\/button><\/li><li><button type='button' id='mc_week-mc-948a6a8e8cd15db324902317a630b853' data-href='https:\/\/novo.esocvp.org\/index.php\/sbv-dae-suporte-basico-de-vida-com-desfibrilhacao-automatica-externa\/?cid=mc-948a6a8e8cd15db324902317a630b853&#038;dy=7&#038;month=8&#038;time=week&#038;yr=2026' class='mc-navigation-button week'>Semana<\/button><\/li><li><button type='button' id='mc_day-mc-948a6a8e8cd15db324902317a630b853' data-href='https:\/\/novo.esocvp.org\/index.php\/sbv-dae-suporte-basico-de-vida-com-desfibrilhacao-automatica-externa\/?cid=mc-948a6a8e8cd15db324902317a630b853&#038;dy=7&#038;time=day' class='mc-navigation-button day'>Dia<\/button><li><\/ul><\/div><div class=\"my-calendar-date-switcher\"><form class=\"mc-date-switcher\" action=\"https:\/\/novo.esocvp.org\/index.php\/wp-json\/wp\/v2\/pages\/538\/\" method=\"get\"><div><input type=\"hidden\" name=\"cid\" value=\"mc-948a6a8e8cd15db324902317a630b853\" \/> <label class=\"maybe-hide\" for=\"mc-948a6a8e8cd15db324902317a630b853-month\">M\u00eas<\/label> <select id=\"mc-948a6a8e8cd15db324902317a630b853-month\" name=\"month\">\n<option value='1'>Janeiro<\/option>\n<option value='2'>Fevereiro<\/option>\n<option value='3'>Mar\u00e7o<\/option>\n<option value='4'>Abril<\/option>\n<option value='5'>Maio<\/option>\n<option value='6'>Junho<\/option>\n<option value='7'>Julho<\/option>\n<option value='8'>Agosto<\/option>\n<option value='9' selected='selected'>Setembro<\/option>\n<option value='10'>Outubro<\/option>\n<option value='11'>Novembro<\/option>\n<option value='12'>Dezembro<\/option>\n<\/select>\n <label class=\"maybe-hide\" for=\"mc-948a6a8e8cd15db324902317a630b853-year\">Ano<\/label> <select id=\"mc-948a6a8e8cd15db324902317a630b853-year\" name=\"yr\">\n<option value=\"2025\">2025<\/option>\n<option value=\"2026\" selected='selected'>2026<\/option>\n<\/select> <input type=\"submit\" class=\"mc-button\" id=\"mc-948a6a8e8cd15db324902317a630b853-button\" value=\"Ir\" \/><\/div><\/form><\/div>\r\n\t\t<div class=\"my-calendar-nav\">\r\n\t\t\t<ul>\r\n\t\t\t\t<li class=\"my-calendar-prev\"><button type=\"button\" class=\"mc-navigation-button\" id=\"mc_previous_mc-948a6a8e8cd15db324902317a630b853\" data-href=\"https:\/\/novo.esocvp.org\/index.php\/sbv-dae-suporte-basico-de-vida-com-desfibrilhacao-automatica-externa\/?cid=mc-948a6a8e8cd15db324902317a630b853&#038;dy&#038;month=8&#038;time=month&#038;yr=2026\"><span class=\"mc-icon\" aria-hidden=\"true\"><\/span><span class=\"maybe-hide\">Anterior <\/span><\/button><\/li><li class=\"my-calendar-today\"><button type=\"button\" id=\"mc_today_mc-948a6a8e8cd15db324902317a630b853\" data-href=\"https:\/\/novo.esocvp.org\/index.php\/sbv-dae-suporte-basico-de-vida-com-desfibrilhacao-automatica-externa\/?cid=mc-948a6a8e8cd15db324902317a630b853\" class=\"mc-navigation-button today mc-active\" aria-current=\"true\"><span class=\"mc-icon\" aria-hidden=\"true\"><\/span>Hoje<\/button><\/li><li class=\"my-calendar-next\"><button type=\"button\" class=\"mc-navigation-button\" id=\"mc_next_mc-948a6a8e8cd15db324902317a630b853\" data-href=\"https:\/\/novo.esocvp.org\/index.php\/sbv-dae-suporte-basico-de-vida-com-desfibrilhacao-automatica-externa\/?cid=mc-948a6a8e8cd15db324902317a630b853&#038;dy&#038;month=10&#038;time=month&#038;yr=2026\"><span class=\"maybe-hide\">Pr\u00f3ximo <\/span><span class=\"mc-icon\" aria-hidden=\"true\"><\/span><\/button><\/li>\r\n\t\t\t<\/ul>\r\n\t\t<\/div><\/div>\n<\/nav>\n<div class=\"mc-content\">\n<table class='my-calendar-table' aria-labelledby='mc_head_mc-948a6a8e8cd15db324902317a630b853'>\n<thead>\n\t<tr class='mc-row'>\n\t\t<th scope=\"col\" class='day-heading mon'><abbr title=\"Segunda-feira\" aria-hidden=\"true\">Seg<\/abbr><span class=\"screen-reader-text\">Segunda-feira<\/span><\/th>\n\n\t\t<th scope=\"col\" class='day-heading tues'><abbr title=\"Ter\u00e7a-feira\" aria-hidden=\"true\">Ter<\/abbr><span class=\"screen-reader-text\">Ter\u00e7a-feira<\/span><\/th>\n\n\t\t<th scope=\"col\" class='day-heading wed'><abbr title=\"Quarta-feira\" aria-hidden=\"true\">Qua<\/abbr><span class=\"screen-reader-text\">Quarta-feira<\/span><\/th>\n\n\t\t<th scope=\"col\" class='day-heading thur'><abbr title=\"Quinta-feira\" aria-hidden=\"true\">Qui<\/abbr><span class=\"screen-reader-text\">Quinta-feira<\/span><\/th>\n\n\t\t<th scope=\"col\" class='day-heading fri'><abbr title=\"Sexta-feira\" aria-hidden=\"true\">Sex<\/abbr><span class=\"screen-reader-text\">Sexta-feira<\/span><\/th>\n\n\t\t<th scope=\"col\" class='weekend-heading sat'><abbr title=\"S\u00e1bado\" aria-hidden=\"true\">S\u00e1b<\/abbr><span class=\"screen-reader-text\">S\u00e1bado<\/span><\/th>\n\n\t\t<th scope=\"col\" class='weekend-heading sun'><abbr title=\"Domingo\" aria-hidden=\"true\">Dom<\/abbr><span class=\"screen-reader-text\">Domingo<\/span><\/th>\n\t<\/tr>\n<\/thead>\n<tbody>\n<tr class='mc-row'><td class='no-events segunda-feira seg past-day past-date  nextmonth no-events day-with-date'><div class='mc-date-container'><span class='mc-date no-events'><span aria-hidden='true'>31<\/span><span class='screen-reader-text'>31 de Agosto, 2026<\/span><\/span><\/div>\n<\/td>\n<td class='no-events tera-feira ter past-day past-date   no-events day-with-date'><div class='mc-date-container'><span class='mc-date no-events'><span aria-hidden='true'>1<\/span><span class='screen-reader-text'>1 de Setembro, 2026<\/span><\/span><\/div>\n<\/td>\n<td aria-current=\"date\" class='no-events quarta-feira qua current-day   no-events day-with-date'><div class='mc-date-container'><span class='mc-date no-events'><span aria-hidden='true'>2<\/span><span class='screen-reader-text'>2 de Setembro, 2026<\/span><\/span><\/div>\n<\/td>\n<td class='no-events quinta-feira qui future-day   no-events day-with-date'><div class='mc-date-container'><span class='mc-date no-events'><span aria-hidden='true'>3<\/span><span class='screen-reader-text'>3 de Setembro, 2026<\/span><\/span><\/div>\n<\/td>\n<td class='no-events sexta-feira sex future-day   no-events day-with-date'><div class='mc-date-container'><span class='mc-date no-events'><span aria-hidden='true'>4<\/span><span class='screen-reader-text'>4 de Setembro, 2026<\/span><\/span><\/div>\n<\/td>\n<td class='no-events sbado sb future-day weekend  no-events day-with-date'><div class='mc-date-container'><span class='mc-date no-events'><span aria-hidden='true'>5<\/span><span class='screen-reader-text'>5 de Setembro, 2026<\/span><\/span><\/div>\n<\/td>\n<td class='no-events domingo dom future-day weekend  no-events day-with-date'><div class='mc-date-container'><span class='mc-date no-events'><span aria-hidden='true'>6<\/span><span class='screen-reader-text'>6 de Setembro, 2026<\/span><\/span><\/div>\n<\/td>\n<\/tr>\n<!-- End Event Row -->\n<tr class='mc-row'><td class='no-events segunda-feira seg future-day   no-events day-with-date'><div class='mc-date-container'><span class='mc-date no-events'><span aria-hidden='true'>7<\/span><span class='screen-reader-text'>7 de Setembro, 2026<\/span><\/span><\/div>\n<\/td>\n<td class='no-events tera-feira ter future-day   no-events day-with-date'><div class='mc-date-container'><span class='mc-date no-events'><span aria-hidden='true'>8<\/span><span class='screen-reader-text'>8 de Setembro, 2026<\/span><\/span><\/div>\n<\/td>\n<td class='no-events quarta-feira qua future-day   no-events day-with-date'><div class='mc-date-container'><span class='mc-date no-events'><span aria-hidden='true'>9<\/span><span class='screen-reader-text'>9 de Setembro, 2026<\/span><\/span><\/div>\n<\/td>\n<td class='no-events quinta-feira qui future-day   no-events day-with-date'><div class='mc-date-container'><span class='mc-date no-events'><span aria-hidden='true'>10<\/span><span class='screen-reader-text'>10 de Setembro, 2026<\/span><\/span><\/div>\n<\/td>\n<td class='no-events sexta-feira sex future-day   no-events day-with-date'><div class='mc-date-container'><span class='mc-date no-events'><span aria-hidden='true'>11<\/span><span class='screen-reader-text'>11 de Setembro, 2026<\/span><\/span><\/div>\n<\/td>\n<td class='no-events sbado sb future-day weekend  no-events day-with-date'><div class='mc-date-container'><span class='mc-date no-events'><span aria-hidden='true'>12<\/span><span class='screen-reader-text'>12 de Setembro, 2026<\/span><\/span><\/div>\n<\/td>\n<td class='no-events domingo dom future-day weekend  no-events day-with-date'><div class='mc-date-container'><span class='mc-date no-events'><span aria-hidden='true'>13<\/span><span class='screen-reader-text'>13 de Setembro, 2026<\/span><\/span><\/div>\n<\/td>\n<\/tr>\n<!-- End Event Row -->\n<tr class='mc-row'><td id='calendar-2026-09-14' class='mc-events segunda-feira seg future-day   has-events author1 mcat_sbvdae day-with-date'><div class='mc-date-container'>\n\t<span class='mc-date'><span aria-hidden='true' class='mc-day-number'>14<\/span><span class='screen-reader-text mc-day-date'>14 de Setembro, 2026<\/span><span class=\"event-icon\" aria-hidden=\"true\">&#9679;<\/span><span class=\"screen-reader-text\"><span class=\"mc-list-details event-count\">(5 events)<\/span><\/span><\/span><\/div><article id='mc_calendar_14_224-calendar-224' class='mc-mc_calendar_224 calendar-event mc_sbvdae mc_morada-eso  future-event mc_primary_sbv-dae nonrecurring mc-8-horas mc-start-09-00 ungrouped mc-event-171 mc-events mc-event mc_rel_sbvdae'><header>\t<h3 class='event-title summary' id='mc_224-title-mc-948a6a8e8cd15db324902317a630b853'><svg style=\"fill:#ffffff\" focusable=\"false\" role=\"img\" aria-labelledby=\"cat_1-22487\" class=\"category-icon\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 576 512\"><!-- Font Awesome Free 5.15.3 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license\/free (Icons: CC BY 4.0, Fonts: SIL OFL 1.1, Code: MIT License) --><title id='cat_1-22487'>Categoria: SBV\/DAE<\/title><path d=\"M0 80v352c0 26.5 21.5 48 48 48h48V32H48C21.5 32 0 53.5 0 80zm128 400h320V32H128v448zm64-248c0-4.4 3.6-8 8-8h56v-56c0-4.4 3.6-8 8-8h48c4.4 0 8 3.6 8 8v56h56c4.4 0 8 3.6 8 8v48c0 4.4-3.6 8-8 8h-56v56c0 4.4-3.6 8-8 8h-48c-4.4 0-8-3.6-8-8v-56h-56c-4.4 0-8-3.6-8-8v-48zM528 32h-48v448h48c26.5 0 48-21.5 48-48V80c0-26.5-21.5-48-48-48z\"\/><\/svg> <div class=\"event-title-container\">SBV\/DAE<\/div><\/h3>\n<\/header><\/article>\n<\/td>\n<td class='no-events tera-feira ter future-day   no-events day-with-date'><div class='mc-date-container'><span class='mc-date no-events'><span aria-hidden='true'>15<\/span><span class='screen-reader-text'>15 de Setembro, 2026<\/span><\/span><\/div>\n<\/td>\n<td class='no-events quarta-feira qua future-day   no-events day-with-date'><div class='mc-date-container'><span class='mc-date no-events'><span aria-hidden='true'>16<\/span><span class='screen-reader-text'>16 de Setembro, 2026<\/span><\/span><\/div>\n<\/td>\n<td class='no-events quinta-feira qui future-day   no-events day-with-date'><div class='mc-date-container'><span class='mc-date no-events'><span aria-hidden='true'>17<\/span><span class='screen-reader-text'>17 de Setembro, 2026<\/span><\/span><\/div>\n<\/td>\n<td class='no-events sexta-feira sex future-day   no-events day-with-date'><div class='mc-date-container'><span class='mc-date no-events'><span aria-hidden='true'>18<\/span><span class='screen-reader-text'>18 de Setembro, 2026<\/span><\/span><\/div>\n<\/td>\n<td class='no-events sbado sb future-day weekend  no-events day-with-date'><div class='mc-date-container'><span class='mc-date no-events'><span aria-hidden='true'>19<\/span><span class='screen-reader-text'>19 de Setembro, 2026<\/span><\/span><\/div>\n<\/td>\n<td class='no-events domingo dom future-day weekend  no-events day-with-date'><div class='mc-date-container'><span class='mc-date no-events'><span aria-hidden='true'>20<\/span><span class='screen-reader-text'>20 de Setembro, 2026<\/span><\/span><\/div>\n<\/td>\n<\/tr>\n<!-- End Event Row -->\n<tr class='mc-row'><td class='no-events segunda-feira seg future-day   no-events day-with-date'><div class='mc-date-container'><span class='mc-date no-events'><span aria-hidden='true'>21<\/span><span class='screen-reader-text'>21 de Setembro, 2026<\/span><\/span><\/div>\n<\/td>\n<td class='no-events tera-feira ter future-day   no-events day-with-date'><div class='mc-date-container'><span class='mc-date no-events'><span aria-hidden='true'>22<\/span><span class='screen-reader-text'>22 de Setembro, 2026<\/span><\/span><\/div>\n<\/td>\n<td class='no-events quarta-feira qua future-day   no-events day-with-date'><div class='mc-date-container'><span class='mc-date no-events'><span aria-hidden='true'>23<\/span><span class='screen-reader-text'>23 de Setembro, 2026<\/span><\/span><\/div>\n<\/td>\n<td class='no-events quinta-feira qui future-day   no-events day-with-date'><div class='mc-date-container'><span class='mc-date no-events'><span aria-hidden='true'>24<\/span><span class='screen-reader-text'>24 de Setembro, 2026<\/span><\/span><\/div>\n<\/td>\n<td class='no-events sexta-feira sex future-day   no-events day-with-date'><div class='mc-date-container'><span class='mc-date no-events'><span aria-hidden='true'>25<\/span><span class='screen-reader-text'>25 de Setembro, 2026<\/span><\/span><\/div>\n<\/td>\n<td id='calendar-2026-09-26' class='mc-events sbado sb future-day weekend  has-events author1 mcat_sbvdae day-with-date'><div class='mc-date-container'>\n\t<span class='mc-date'><span aria-hidden='true' class='mc-day-number'>26<\/span><span class='screen-reader-text mc-day-date'>26 de Setembro, 2026<\/span><span class=\"event-icon\" aria-hidden=\"true\">&#9679;<\/span><span class=\"screen-reader-text\"><span class=\"mc-list-details event-count\">(5 events)<\/span><\/span><\/span><\/div><article id='mc_calendar_26_231-calendar-231' class='mc-mc_calendar_231 calendar-event mc_sbvdae mc_morada-eso  future-event mc_primary_sbv-dae nonrecurring mc-8-horas mc-start-09-00 ungrouped mc-event-178 mc-events mc-event mc_rel_sbvdae'><header>\t<h3 class='event-title summary' id='mc_231-title-mc-948a6a8e8cd15db324902317a630b853'><svg style=\"fill:#ffffff\" focusable=\"false\" role=\"img\" aria-labelledby=\"cat_1-23187\" class=\"category-icon\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 576 512\"><!-- Font Awesome Free 5.15.3 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license\/free (Icons: CC BY 4.0, Fonts: SIL OFL 1.1, Code: MIT License) --><title id='cat_1-23187'>Categoria: SBV\/DAE<\/title><path d=\"M0 80v352c0 26.5 21.5 48 48 48h48V32H48C21.5 32 0 53.5 0 80zm128 400h320V32H128v448zm64-248c0-4.4 3.6-8 8-8h56v-56c0-4.4 3.6-8 8-8h48c4.4 0 8 3.6 8 8v56h56c4.4 0 8 3.6 8 8v48c0 4.4-3.6 8-8 8h-56v56c0 4.4-3.6 8-8 8h-48c-4.4 0-8-3.6-8-8v-56h-56c-4.4 0-8-3.6-8-8v-48zM528 32h-48v448h48c26.5 0 48-21.5 48-48V80c0-26.5-21.5-48-48-48z\"\/><\/svg> <div class=\"event-title-container\">SBV\/DAE<\/div><\/h3>\n<\/header><\/article>\n<\/td>\n<td class='no-events domingo dom future-day weekend  no-events day-with-date'><div class='mc-date-container'><span class='mc-date no-events'><span aria-hidden='true'>27<\/span><span class='screen-reader-text'>27 de Setembro, 2026<\/span><\/span><\/div>\n<\/td>\n<\/tr>\n<!-- End Event Row -->\n<tr class='mc-row'><td class='no-events segunda-feira seg future-day   no-events day-with-date'><div class='mc-date-container'><span class='mc-date no-events'><span aria-hidden='true'>28<\/span><span class='screen-reader-text'>28 de Setembro, 2026<\/span><\/span><\/div>\n<\/td>\n<td class='no-events tera-feira ter future-day   no-events day-with-date'><div class='mc-date-container'><span class='mc-date no-events'><span aria-hidden='true'>29<\/span><span class='screen-reader-text'>29 de Setembro, 2026<\/span><\/span><\/div>\n<\/td>\n<td class='no-events quarta-feira qua future-day   no-events day-with-date'><div class='mc-date-container'><span class='mc-date no-events'><span aria-hidden='true'>30<\/span><span class='screen-reader-text'>30 de Setembro, 2026<\/span><\/span><\/div>\n<\/td>\n<td class='no-events quinta-feira qui future-day  nextmonth no-events day-with-date'><div class='mc-date-container'><span class='mc-date no-events'><span aria-hidden='true'>1<\/span><span class='screen-reader-text'>1 de Outubro, 2026<\/span><\/span><\/div>\n<\/td>\n<td class='no-events sexta-feira sex future-day  nextmonth no-events day-with-date'><div class='mc-date-container'><span class='mc-date no-events'><span aria-hidden='true'>2<\/span><span class='screen-reader-text'>2 de Outubro, 2026<\/span><\/span><\/div>\n<\/td>\n<td class='no-events sbado sb future-day weekend nextmonth no-events day-with-date'><div class='mc-date-container'><span class='mc-date no-events'><span aria-hidden='true'>3<\/span><span class='screen-reader-text'>3 de Outubro, 2026<\/span><\/span><\/div>\n<\/td>\n<td class='no-events domingo dom future-day weekend nextmonth no-events day-with-date'><div class='mc-date-container'><span class='mc-date no-events'><span aria-hidden='true'>4<\/span><span class='screen-reader-text'>4 de Outubro, 2026<\/span><\/span><\/div>\n<\/td>\n<\/tr>\n<!-- End Event Row -->\n\n<\/tbody>\n<\/table><\/div><!-- .mc-content -->\n<nav class=\"my-calendar-navigation\" aria-label=\"Calendar (bottom)\">\n<div class=\"mc_bottomnav my-calendar-footer\"><div class=\"category-key has-icons\"><h2 class=\"maybe-hide\">Categorias do Evento<\/h2>\n<ul>\n<li class=\"cat_sbvdae current\"><button type=\"button\" class=\"mc-navigation-button\" id=\"mc_cat_1-mc-948a6a8e8cd15db324902317a630b853\" data-href=\"https:\/\/novo.esocvp.org\/index.php\/wp-json\/wp\/v2\/pages\/538\/\" aria-pressed=\"true\"><span class=\"category-color-sample svg\" style=\"background:#1003a3;\"><svg style=\"fill:#ffffff\" focusable=\"false\" role=\"img\" aria-labelledby=\"cat_1\" class=\"category-icon\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 576 512\"><!-- Font Awesome Free 5.15.3 by @fontawesome - https:\/\/fontawesome.com License - https:\/\/fontawesome.com\/license\/free (Icons: CC BY 4.0, Fonts: SIL OFL 1.1, Code: MIT License) --><title id='cat_1'>SBV\/DAE<\/title><path d=\"M0 80v352c0 26.5 21.5 48 48 48h48V32H48C21.5 32 0 53.5 0 80zm128 400h320V32H128v448zm64-248c0-4.4 3.6-8 8-8h56v-56c0-4.4 3.6-8 8-8h48c4.4 0 8 3.6 8 8v56h56c4.4 0 8 3.6 8 8v48c0 4.4-3.6 8-8 8h-56v56c0 4.4-3.6 8-8 8h-48c-4.4 0-8-3.6-8-8v-56h-56c-4.4 0-8-3.6-8-8v-48zM528 32h-48v448h48c26.5 0 48-21.5 48-48V80c0-26.5-21.5-48-48-48z\"\/><\/svg><\/span>SBV\/DAE<\/button><\/li><li class='all-categories'><span class='mc-active' id='mc_cat_all-mc-948a6a8e8cd15db324902317a630b853' tabindex='-1'>Todas as categorias<\/span><\/li><\/ul><\/div><div class='mc-print'><a id='mc_print-mc-948a6a8e8cd15db324902317a630b853' href='https:\/\/novo.esocvp.org?cid=mc-print-view&#038;dy=1&#038;href=https%3A%2F%2Fnovo.esocvp.org%2Findex.php%2Fwp-json%2Fwp%2Fv2%2Fpages%2F538%2F&#038;mcat=1&#038;month=9&#038;time=month&#038;yr=2026' rel='nofollow'><span class='mc-icon' aria-hidden='true'><\/span>Print<span class=\"maybe-hide\"> View<\/span><\/a><\/div><\/div>\n<\/nav>\n\r\n<\/div><!-- Close Main My Calendar Wrapper -->\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Dura\u00e7\u00e3o: 7 horas Objetivo: Adquirir compet\u00eancias que lhe permitam realizar corretamente manobras de SBV com utiliza\u00e7\u00e3o de um Desfibrilhador Autom\u00e1tico Externo (DAE), numa v\u00edtima em paragem cardiorrespirat\u00f3ria. Destinat\u00e1rios: Este curso destina-se a profissionais de sa\u00fade e leigos, com dom\u00ednio da l\u00edngua portuguesa e com idade m\u00ednima de 16 anos. Conte\u00fados Program\u00e1ticos: Cadeia de Sobreviv\u00eancia; riscos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"wp-custom-template-curso-sbv-dae","meta":{"_mc_calendar":[],"footnotes":""},"class_list":["post-538","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/novo.esocvp.org\/index.php\/wp-json\/wp\/v2\/pages\/538","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novo.esocvp.org\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/novo.esocvp.org\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/novo.esocvp.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/novo.esocvp.org\/index.php\/wp-json\/wp\/v2\/comments?post=538"}],"version-history":[{"count":17,"href":"https:\/\/novo.esocvp.org\/index.php\/wp-json\/wp\/v2\/pages\/538\/revisions"}],"predecessor-version":[{"id":1238,"href":"https:\/\/novo.esocvp.org\/index.php\/wp-json\/wp\/v2\/pages\/538\/revisions\/1238"}],"wp:attachment":[{"href":"https:\/\/novo.esocvp.org\/index.php\/wp-json\/wp\/v2\/media?parent=538"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}